{"id":28950,"date":"2022-03-02T12:53:53","date_gmt":"2022-03-02T15:53:53","guid":{"rendered":"https:\/\/www.muniquintero.cl\/?p=28950"},"modified":"2022-03-02T12:57:01","modified_gmt":"2022-03-02T15:57:01","slug":"vuelven-las-ferias-de-emprendimiento-a-quintero","status":"publish","type":"post","link":"https:\/\/www.muniquintero.cl\/index.php\/2022\/03\/02\/vuelven-las-ferias-de-emprendimiento-a-quintero\/","title":{"rendered":"Vuelven las Ferias de Emprendimiento a Quintero"},"content":{"rendered":"\n<p>Con el regreso de Quintero a fase 3 en el Plan Paso a Paso, se retomar\u00e1n las actividades de la Oficina de Fomento Productivo del municipio, suspendidas como medida preventiva en el contexto de la pandemia.<\/p>\n\n\n\n<p>Jorge Peralta encargado de la Oficina de Fomento Productivo inform\u00f3 que, \u201ccomenzamos nuevamente a funcionar con la feria en la Plaza Ignacio Carera Pinto, como es de costumbre los d\u00edas viernes y s\u00e1bado a partir de este fin de semana 4 y 5 de marzo, desde las 10 de la ma\u00f1ana hasta las 6 de la tarde\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3030-1024x683.jpg\" alt=\"\" class=\"wp-image-28952\" srcset=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3030-1024x683.jpg 1024w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3030-300x200.jpg 300w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3030-768x512.jpg 768w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3030-1536x1024.jpg 1536w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3030-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/Jorge-Peralta.mp3\"><\/audio><figcaption>Jorge Peralta<\/figcaption><\/figure>\n\n\n\n<p>Estas ferias destacan porque los participantes son exclusivamente de la comuna, \u201cson emprendedores quinteranos y de las localidades rurales de Quintero, tenemos mucho expositor de Loncura, Ritoque, Valle Alegre, etc\u201d, destac\u00f3 Peralta.<\/p>\n\n\n\n<p>Respecto a este tema, las personas interesadas en participar en las ferias organizadas, deben dirigirse a la Oficina de Fomento Productivo ubicada en calle Arturo Prat # 1960 2\u00ba piso Quintero, \u201csolamente con 4 fotos de los productos que venden, m\u00e1s 1 foto individual que las pueden traer en un pendrive, celular o enviar por correo, m\u00e1s el carnet de identidad y la Ficha de Protecci\u00f3n Social que no es excluyente\u201d, explic\u00f3 el encargado de la oficina.<\/p>\n\n\n\n<p>Para el presente a\u00f1o 2022, la Oficina de Fomento Productivo de la Municipalidad de Quintero, tiene contemplada la organizaci\u00f3n de Ferias de Emprendimiento, que incluye todo tipo de rubros, Eco Ferias con expositores del \u00e1rea de la ancestralidad, verduras, hortalizas org\u00e1nicas, manualidades, artesan\u00eda, Ferias de la Mujer, Ferias Regionales y Ferias Rurales. &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"28954\" src=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3018-1024x683.jpg\" alt=\"\" class=\"wp-image-28954\" srcset=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3018-1024x683.jpg 1024w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3018-300x200.jpg 300w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3018-768x512.jpg 768w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3018-1536x1024.jpg 1536w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3018-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"28955\" src=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3033-1024x683.jpg\" alt=\"\" class=\"wp-image-28955\" srcset=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3033-1024x683.jpg 1024w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3033-300x200.jpg 300w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3033-768x512.jpg 768w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3033-1536x1024.jpg 1536w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/03\/IMG_3033-2048x1366.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Con el regreso de Quintero a fase 3 en el Plan Paso a Paso, se retomar\u00e1n las actividades de la Oficina de Fomento Productivo del municipio, suspendidas como medida preventiva en el contexto de la pandemia. Jorge Peralta encargado de la Oficina de Fomento Productivo inform\u00f3 que, \u201ccomenzamos nuevamente a funcionar con la feria en [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":28951,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-28950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/28950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/comments?post=28950"}],"version-history":[{"count":2,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/28950\/revisions"}],"predecessor-version":[{"id":28957,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/28950\/revisions\/28957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/media\/28951"}],"wp:attachment":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/media?parent=28950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/categories?post=28950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/tags?post=28950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}