{"id":28873,"date":"2022-02-21T18:13:51","date_gmt":"2022-02-21T21:13:51","guid":{"rendered":"https:\/\/www.muniquintero.cl\/?p=28873"},"modified":"2022-02-21T18:19:09","modified_gmt":"2022-02-21T21:19:09","slug":"funcionarios-de-la-salud-municipal-de-quintero-denuncian-amenazas-por-parte-de-pacientes","status":"publish","type":"post","link":"https:\/\/www.muniquintero.cl\/index.php\/2022\/02\/21\/funcionarios-de-la-salud-municipal-de-quintero-denuncian-amenazas-por-parte-de-pacientes\/","title":{"rendered":"Funcionarios de la Salud Municipal de Quintero denuncian amenazas por parte de pacientes"},"content":{"rendered":"\n<p>Luego de que uno de los m\u00e9dicos de la Posta de Salud Rural de Loncura dependiente de la Municipalidad de Quintero, fuera amenazado y agredido por un paciente el s\u00e1bado 19 de febrero, los funcionarios de la salud realizaron la denuncia y se reunieron con autoridades policiales y municipales para solicitar m\u00e1s seguridad.<\/p>\n\n\n\n<p>Esta agresi\u00f3n se sum\u00f3 a otras que en el \u00faltimo tiempo, han recibido enfermeras, conductores y ambulancias mientras atienden pacientes o se dirigen a prestar auxilio a emergencias, lo que motiv\u00f3 la reuni\u00f3n efectuada el lunes 21 de febrero.<\/p>\n\n\n\n<p>Al respecto Daniel R\u00edos presidente de la Confederaci\u00f3n Nacional de Funcionarios de la Salud Municipal CONFUSAM de Quintero, plante\u00f3 que&nbsp; \u201cestamos bastante alertas con la situaci\u00f3n que pas\u00f3 el fin de semana, porque es una amenaza de muerte en contra de un funcionario, nosotros le pedimos a la comunidad que tome conciencia que la gente que est\u00e1 en el consultorio, los funcionarios que est\u00e1n ah\u00ed trabajando est\u00e1n para entregar un servicio a la comunidad, pido tambi\u00e9n que dejemos la xenofobia de lado y todo tema que lleve a la violencia\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/02\/DANIEL-RI\u0301OS-CONFUSAM.mp3\"><\/audio><figcaption>Daniel R\u00edos<\/figcaption><\/figure>\n\n\n\n<p>En tanto Carlos Castillo, presidente de la Confederaci\u00f3n Nacional de Asociaciones de Funcionarias y Funcionarios de Atenci\u00f3n Primaria Municipal, COTRASAM de Quintero, dijo que, \u201cvamos a recibir harto apoyo tanto de Seguridad Ciudadana como de Carabineros, para prevenir las agresiones que estamos sufriendo en el Consultorio de Loncura, el s\u00e1bado tuvimos una agresi\u00f3n y una amenaza de muerte al doctor que estaba de turno y eso deriv\u00f3 en que qued\u00e1ramos sin m\u00e9dico, afectando a toda la poblaci\u00f3n\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/02\/CARLOS-CASTILLO.mp3\"><\/audio><figcaption>Carlos Castillo<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/02\/IMG_2516-1024x683.jpg\" alt=\"\" class=\"wp-image-28877\" srcset=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/02\/IMG_2516-1024x683.jpg 1024w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/02\/IMG_2516-300x200.jpg 300w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/02\/IMG_2516-768x512.jpg 768w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/02\/IMG_2516-1536x1024.jpg 1536w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/02\/IMG_2516-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Ante esto el teniente de Carabineros Erick Sanzana, Subcomisario de Quintero, plante\u00f3 que \u201cel d\u00eda de hoy nos hemos reunido con el personal de salud de la Municipalidad de Quintero con la finalidad de realizar coordinaciones en materia de seguridad, donde Carabineros va a apoyar mediante patrullajes preventivos y rondas peri\u00f3dicas, para verificar que todo se encuentre en orden y no sean v\u00edctima de delito\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/02\/ERICK-SANZANA-CARABINEROS.mp3\"><\/audio><figcaption>Erick Sanzana<\/figcaption><\/figure>\n\n\n\n<p>En esta misma l\u00ednea, Patricio Aran\u00edbar, Director de Seguridad P\u00fablica de la Municipalidad de Quintero se\u00f1al\u00f3 que \u201cnosotros igualmente tenemos un cuerpo de Seguridad Ciudadana que ha contribuido de buena manera pero conforme a nuestras facultades y desde es punto de vista estamos llano a hacer rondas preventivas en la Posta de Loncura en este caso preciso donde ocurri\u00f3 esta tem\u00e1tica\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/02\/PATRICIO-ARANIBAR-SEGURIDAD-CIUDADANA.mp3\"><\/audio><figcaption>Patricio Aran\u00edbar<\/figcaption><\/figure>\n\n\n\n<p>Finalmente, el director de Gabinete Municipal V\u00edctor Hugo Fern\u00e1ndez adelant\u00f3 que, \u201cel alcalde don Mauricio Carrasco nos ha pedido que generemos una mesa t\u00e9cnica de trabajo en conjunto con Carabineros de Chile y nuestra Direcci\u00f3n de Seguridad P\u00fablica en conjunto con el Departamento de Salud y sus asociaciones\u201d, para asegurar la salud e integridad f\u00edsica de los trabajadores.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/02\/VICTO-FERNANDEZ-GABINETE.mp3\"><\/audio><figcaption>V\u00edctor Fern\u00e1ndez<\/figcaption><\/figure>\n\n\n\n<p>Como primer acuerdo, se revisar\u00e1n los protocolos de atenci\u00f3n de p\u00fablico y se fiscalizar\u00e1 a la empresa de seguridad del recinto de salud, adem\u00e1s de instar a los funcionarios a hacer las denuncias respectivas para que estos delitos sean perseguidos por tribunales de justicia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de que uno de los m\u00e9dicos de la Posta de Salud Rural de Loncura dependiente de la Municipalidad de Quintero, fuera amenazado y agredido por un paciente el s\u00e1bado 19 de febrero, los funcionarios de la salud realizaron la denuncia y se reunieron con autoridades policiales y municipales para solicitar m\u00e1s seguridad. Esta agresi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":28874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-28873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/28873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/comments?post=28873"}],"version-history":[{"count":3,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/28873\/revisions"}],"predecessor-version":[{"id":28884,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/28873\/revisions\/28884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/media\/28874"}],"wp:attachment":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/media?parent=28873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/categories?post=28873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/tags?post=28873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}