{"id":27323,"date":"2022-01-25T09:11:05","date_gmt":"2022-01-25T12:11:05","guid":{"rendered":"https:\/\/www.muniquintero.cl\/?p=27323"},"modified":"2022-01-25T09:11:07","modified_gmt":"2022-01-25T12:11:07","slug":"departamento-de-salud-municipal-informa-del-plan-de-manejo-del-coronavirus","status":"publish","type":"post","link":"https:\/\/www.muniquintero.cl\/index.php\/2022\/01\/25\/departamento-de-salud-municipal-informa-del-plan-de-manejo-del-coronavirus\/","title":{"rendered":"Departamento de Salud Municipal informa del Plan de Manejo del Coronavirus"},"content":{"rendered":"\n<p>A contar del 20 de enero de 2022 el Ministerio de Salud modific\u00f3 el Plan de Manejo del Coronavirus a nivel nacional, ante la aparici\u00f3n de la variante \u00d3micron y su alta tasa de contagios.<\/p>\n\n\n\n<p>Los cambios incorporados por el Gobierno en la gesti\u00f3n de la pandemia no tan s\u00f3lo implican una reducci\u00f3n de d\u00edas de cuarentena en caso de dar positivo sino que adem\u00e1s, hay una variaci\u00f3n en los t\u00e9rminos y procedimientos que se aplicaban anteriormente.<\/p>\n\n\n\n<p>Nataly Moraga enfermera encargada de epidemiolog\u00eda del Departamento de Salud Municipal de Quintero, se\u00f1al\u00f3 que este cambio b\u00e1sicamente \u201cnos vamos a centrar principalmente en el caso confirmado, aquella persona que est\u00e1 confirmada como caso Covid ya sea por PCR o Test de Ant\u00edgeno\u201d.<\/p>\n\n\n\n<p>\u201cEsta persona se va a aislar 7 d\u00edas en su domicilio, siendo el d\u00eda 0 el d\u00eda que parten los s\u00edntomas o el d\u00eda en que se toma el Test. (\u2026) \u201cUna vez que su resultado da positivo tiene que ubicar a toda la gente que ha estado cerca de \u00e9l sin uso correcto de la mascarilla, a una distancia menor de un metro, 2 d\u00edas antes del inicio de s\u00edntomas o 2 d\u00edas antes de la toma de muestra del examen\u201d, explic\u00f3 la encargada de epidemiolog\u00eda del municipio.<\/p>\n\n\n\n<p>La persona que anteriormente se denominaba <em>Contacto Estrecho<\/em>, con el nuevo Plan de Manejo del Coronavirus pasan a llamarse <em>Alerta Covid<\/em> y \u201cno entrar\u00e1 en cuarentena, no se quedar\u00e1 en casa sino que va a seguir con su vida normal&nbsp; pero con algunas medidas personales, como es la toma de PCR en los pr\u00f3ximos 2 d\u00edas al contacto y automonitoreo de s\u00edntomas\u201d, detall\u00f3 la enfermera del Departamento de Salud Municipal.<\/p>\n\n\n\n<p>Nataly Moraga enfatiz\u00f3 que \u201cen caso de que la persona<em> Alerta Covid<\/em> inicie s\u00edntomas respiratorios o s\u00edntomas sugerentes, debe acercarse lo antes posible a un establecimiento de salud para ser evaluado por un m\u00e9dico y catalogarlo como caso sospecha\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2022\/01\/NATALY-MORAGA.mp3\"><\/audio><figcaption>Nataly Moraga<\/figcaption><\/figure>\n\n\n\n<p>El nuevo Plan de Manejo del Coronavirus tambi\u00e9n incorpora cambios en la gesti\u00f3n administrativa que pueden ser revisados en el siguiente enlace: <a href=\"https:\/\/saludresponde.minsal.cl\/plan-de-manejo-de-coronavirus\/\">https:\/\/saludresponde.minsal.cl\/plan-de-manejo-de-coronavirus\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A contar del 20 de enero de 2022 el Ministerio de Salud modific\u00f3 el Plan de Manejo del Coronavirus a nivel nacional, ante la aparici\u00f3n de la variante \u00d3micron y su alta tasa de contagios. Los cambios incorporados por el Gobierno en la gesti\u00f3n de la pandemia no tan s\u00f3lo implican una reducci\u00f3n de d\u00edas [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":27325,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-27323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/27323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/comments?post=27323"}],"version-history":[{"count":1,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/27323\/revisions"}],"predecessor-version":[{"id":27326,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/27323\/revisions\/27326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/media\/27325"}],"wp:attachment":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/media?parent=27323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/categories?post=27323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/tags?post=27323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}