{"id":27050,"date":"2021-12-23T19:23:38","date_gmt":"2021-12-23T22:23:38","guid":{"rendered":"https:\/\/www.muniquintero.cl\/?p=27050"},"modified":"2021-12-23T19:23:40","modified_gmt":"2021-12-23T22:23:40","slug":"concejo-municipal-sesiono-en-mantagua-y-entrego-nuevo-vehiculo-de-seguridad-ciudadana","status":"publish","type":"post","link":"https:\/\/www.muniquintero.cl\/index.php\/2021\/12\/23\/concejo-municipal-sesiono-en-mantagua-y-entrego-nuevo-vehiculo-de-seguridad-ciudadana\/","title":{"rendered":"Concejo Municipal sesion\u00f3 en Mantagua y entreg\u00f3 nuevo veh\u00edculo de seguridad ciudadana"},"content":{"rendered":"\n<p>Como parte de la nueva pol\u00edtica de gobierno en terreno, el Concejo Municipal de Quintero sesion\u00f3 el mi\u00e9rcoles 22 de diciembre en la localidad de Mantagua y entreg\u00f3 importantes anuncios.<\/p>\n\n\n\n<p>Al respecto el alcalde Mauricio Carrasco Pardo indic\u00f3 que \u201choy d\u00eda nos toc\u00f3 en Mantagua recogiendo las necesidades de los vecinos, participaron muchos dirigentes y vecinos por los temas de salud y seguridad\u201d (\u2026) \u201cnos adjudicamos dos m\u00f3viles, una camioneta y un veh\u00edculo para sumarlos a los que ya ten\u00edamos en seguridad, y uno de ellos va a quedar absolutamente disponible 24 horas para las comunidades rurales\u201d.<\/p>\n\n\n\n<p>\u201cJunto con ello tambi\u00e9n quiero anunciar que nos adjudicamos un convenio de 800 millones de pesos para un nuevo Jard\u00edn Infantil ac\u00e1 en Mantagua\u201d, destac\u00f3 el jefe comunal.<\/p>\n\n\n\n<p>El alcalde Mauricio Carrasco valor\u00f3 adem\u00e1s la participaci\u00f3n activa de los concejales en la gesti\u00f3n municipal, aportando ideas e impulsando iniciativas que refuerzan la gesti\u00f3n del gobierno comunal.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2021\/12\/cun\u0303a-alcalde-concejo.mp3\"><\/audio><figcaption>Mauricio Carrasco<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2021\/12\/IMG_1194-1024x683.jpg\" alt=\"\" class=\"wp-image-27053\" srcset=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2021\/12\/IMG_1194-1024x683.jpg 1024w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2021\/12\/IMG_1194-300x200.jpg 300w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2021\/12\/IMG_1194-768x512.jpg 768w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2021\/12\/IMG_1194-1536x1024.jpg 1536w, https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2021\/12\/IMG_1194-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de la nueva pol\u00edtica de gobierno en terreno, el Concejo Municipal de Quintero sesion\u00f3 el mi\u00e9rcoles 22 de diciembre en la localidad de Mantagua y entreg\u00f3 importantes anuncios. Al respecto el alcalde Mauricio Carrasco Pardo indic\u00f3 que \u201choy d\u00eda nos toc\u00f3 en Mantagua recogiendo las necesidades de los vecinos, participaron muchos dirigentes y [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":27052,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-27050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/27050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/comments?post=27050"}],"version-history":[{"count":1,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/27050\/revisions"}],"predecessor-version":[{"id":27054,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/27050\/revisions\/27054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/media\/27052"}],"wp:attachment":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/media?parent=27050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/categories?post=27050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/tags?post=27050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}