{"id":25526,"date":"2021-06-16T14:47:29","date_gmt":"2021-06-16T17:47:29","guid":{"rendered":"https:\/\/www.muniquintero.cl\/?p=25526"},"modified":"2021-06-16T14:47:31","modified_gmt":"2021-06-16T17:47:31","slug":"ex-vertedero-municipal-sera-reconvertido-en-area-verde","status":"publish","type":"post","link":"https:\/\/www.muniquintero.cl\/index.php\/2021\/06\/16\/ex-vertedero-municipal-sera-reconvertido-en-area-verde\/","title":{"rendered":"Ex Vertedero Municipal ser\u00e1 reconvertido en \u00e1rea verde"},"content":{"rendered":"\n<p>Cuando se cumplen 3 a\u00f1os del proceso de cierre del vertedero en Loncura la municipalidad de Quintero adquirir\u00e1 el terreno para implementar importantes proyectos medioambientales que incluye un centro de atenci\u00f3n integral de mascotas.<\/p>\n\n\n\n<p>El recinto que por m\u00e1s de 30 a\u00f1os acopi\u00f3 no tan s\u00f3lo la basura domiciliaria sino que adem\u00e1s escombros y desechos industriales, hoy se encuentra cerrado por resoluci\u00f3n de la SEREMI de Salud. Desde el a\u00f1o 2018 todos los residuos domiciliarios recolectados en la comuna son trasladados al <em>Relleno Sanitario San Pedro<\/em> ubicado en la comuna de Quillota.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.muniquintero.cl\/wp-content\/uploads\/2021\/06\/Cun\u0303a-alcalde-vertedero.mp3\"><\/audio><figcaption>Mauricio Carrasco \/ Alcalde<\/figcaption><\/figure>\n\n\n\n<p>El alcalde Mauricio Carrasco Pardo tras visitar el lugar inform\u00f3 que \u201clo que estamos revisando hoy d\u00eda es verificar las medidas, ya que el Tribunal Ambiental &nbsp;resolvi\u00f3 que la municipalidad debe comprar este espacio\u201d.<\/p>\n\n\n\n<p>\u201cNosotros vamos a comprar este lugar y aqu\u00ed &nbsp;lo \u00fanico que se va a poder emplazar es un \u00e1rea verde y tambi\u00e9n ac\u00e1 queremos desarrollar un <em>canil<\/em> de la mejor manera, queremos trasladar ac\u00e1 todas las instalaciones de la cl\u00ednica veterinaria, tenemos un proyecto muy bonito\u201d<\/p>\n\n\n\n<p>Actualmente se encuentra en proceso de evaluaci\u00f3n el proyecto denominado \u00abAdquisici\u00f3n del terreno ex vertedero Quintero\u00bb, presentado a la Subsecretar\u00eda de Desarrollo Regional, y que tiene como objetivo aplicar las medidas que otorguen el cierre y sellado definitivo del ex vertedero, para luego establecer la posterior reinserci\u00f3n de la superficie afectada, otorgando una soluci\u00f3n concreta y dar paso a los futuros proyectos que permita el uso del suelo en ese sector de la comuna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando se cumplen 3 a\u00f1os del proceso de cierre del vertedero en Loncura la municipalidad de Quintero adquirir\u00e1 el terreno para implementar importantes proyectos medioambientales que incluye un centro de atenci\u00f3n integral de mascotas. El recinto que por m\u00e1s de 30 a\u00f1os acopi\u00f3 no tan s\u00f3lo la basura domiciliaria sino que adem\u00e1s escombros y desechos [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":25527,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-25526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/25526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/comments?post=25526"}],"version-history":[{"count":1,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/25526\/revisions"}],"predecessor-version":[{"id":25529,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/25526\/revisions\/25529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/media\/25527"}],"wp:attachment":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/media?parent=25526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/categories?post=25526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/tags?post=25526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}