{"id":25046,"date":"2021-03-23T13:38:12","date_gmt":"2021-03-23T16:38:12","guid":{"rendered":"https:\/\/www.muniquintero.cl\/?p=25046"},"modified":"2021-03-23T13:38:14","modified_gmt":"2021-03-23T16:38:14","slug":"pavimentacion-de-calles-en-loncura-pondra-fin-a-anos-de-anegamientos","status":"publish","type":"post","link":"https:\/\/www.muniquintero.cl\/index.php\/2021\/03\/23\/pavimentacion-de-calles-en-loncura-pondra-fin-a-anos-de-anegamientos\/","title":{"rendered":"Pavimentaci\u00f3n de calles en Loncura pondr\u00e1 fin a a\u00f1os de anegamientos"},"content":{"rendered":"\n<p>Durante la \u00faltima sesi\u00f3n del Concejo Municipal de Quintero se aprob\u00f3 la postulaci\u00f3n del proyecto de pavimentaci\u00f3n de las calles Huaylas y Yungay de Loncura, que pondr\u00e1 fin a los anegamientos de las aguas lluvias que por a\u00f1os afecta a los vecinos del sector.<\/p>\n\n\n\n<p>Francisco Jeldes, Director de la Secretar\u00eda Comunal de Planificaci\u00f3n -SECPLA- dijo que \u201cel mi\u00e9rcoles pasado presentamos a la Comisi\u00f3n de Inversiones del Concejo Municipal los avances de este importante proyecto, que no s\u00f3lo considera el punto de evacuaci\u00f3n, sino que tambi\u00e9n la pavimentaci\u00f3n completa del circuito Yungay y Huaylas\u201d.<\/p>\n\n\n\n<p>\u201cPara nosotros es un proyecto importante &nbsp;porque despu\u00e9s de haber saneado sanitariamente esta primera etapa de Loncura nos permite poder empezar a&nbsp; impulsar&nbsp; y &nbsp;gestionar las inversiones necesarias de pavimentaci\u00f3n\u201d (\u2026) \u201cHoy estamos gestionando la aprobaci\u00f3n en el SERVIU, ya tenemos la aprobaci\u00f3n de la autoridad mar\u00edtima para la descarga de evacuaci\u00f3n de aguas lluvias y estamos en las \u00faltimas gestiones de&nbsp; aprobaciones t\u00e9cnicas para obtener los recursos que son cercanos a los 1500 millones de pesos\u201d &nbsp;<\/p>\n\n\n\n<p>Denisse R\u00edos, Ingeniero en Construcci\u00f3n de SECPLA, explic\u00f3 que el proyecto es un circuito que comprende las calles Huaylas, Yungay y Borde Costero que \u201cen metros lineales corresponde a m\u00e1s de un kil\u00f3metro de pavimentaci\u00f3n\u201d (\u2026) \u201ccuenta con un ducto subterr\u00e1neo que recibe el aporte de 4 hect\u00e1reas de aguas lluvias\u201d<\/p>\n\n\n\n<p>&nbsp;\u201cEste es un proyecto que tiene una faja estructural considerable\u201d, con un espesor de 18 cent\u00edmetros de hormig\u00f3n que permitir\u00e1 en el futuro realizar la pavimentaci\u00f3n de las calles colindantes al sector, anticip\u00f3 la Ingeniero de SECPLA.<\/p>\n\n\n\n<p>El Concejal Luis Gatica, presidente de la Comisi\u00f3n de Ordenamiento Territorial explic\u00f3 que en la \u00faltima sesi\u00f3n \u201cya hemos aprobado y se ha resuelto todos los aspectos t\u00e9cnicos para postular esta calle para este a\u00f1o 2021\u201d<\/p>\n\n\n\n<p>Las obras que se ejecutar\u00e1n \u201cvienen a resolver este gran problema que tienen estas dos calles, porque hay una parte que aun no esta pavimentada en la calle Yungay, pero tambi\u00e9n este lugar que se inunda todos los inviernos y la gente tiene cortado los accesos hacia la playa\u201d, (\u2026)&nbsp; \u201ces una buena noticia porque para nosotros Loncura no es el patio trasero, y tiene que progresar de la misma forma como est\u00e1 progresando toda la comuna de Quintero\u201d, concluy\u00f3 el edil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la \u00faltima sesi\u00f3n del Concejo Municipal de Quintero se aprob\u00f3 la postulaci\u00f3n del proyecto de pavimentaci\u00f3n de las calles Huaylas y Yungay de Loncura, que pondr\u00e1 fin a los anegamientos de las aguas lluvias que por a\u00f1os afecta a los vecinos del sector. Francisco Jeldes, Director de la Secretar\u00eda Comunal de Planificaci\u00f3n -SECPLA- dijo [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":25047,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-25046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/25046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/comments?post=25046"}],"version-history":[{"count":1,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/25046\/revisions"}],"predecessor-version":[{"id":25048,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/posts\/25046\/revisions\/25048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/media\/25047"}],"wp:attachment":[{"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/media?parent=25046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/categories?post=25046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muniquintero.cl\/index.php\/wp-json\/wp\/v2\/tags?post=25046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}